<br />
<b>Warning</b>:  Constant WP_DEFAULT_THEME already defined in <b>/home/u580195476/domains/canal-literatura.com/public_html/BLOG/wp/wp-config.php</b> on line <b>24</b><br />
<br />
<b>Warning</b>:  Constant ABSPATH already defined in <b>/home/u580195476/domains/canal-literatura.com/public_html/BLOG/wp/wp-config.php</b> on line <b>32</b><br />
{"id":4066,"date":"2010-05-13T13:21:20","date_gmt":"2010-05-13T11:21:20","guid":{"rendered":"https:\/\/www.canal-literatura.com\/BLOG\/?p=4066"},"modified":"2010-05-12T20:21:39","modified_gmt":"2010-05-12T18:21:39","slug":"en-el-pais-del-ensueno-ideal-por-mar-solana","status":"publish","type":"post","link":"https:\/\/www.canal-literatura.com\/BLOG\/en-el-pais-del-ensueno-ideal-por-mar-solana\/","title":{"rendered":"En el pa\u00eds del \u00abensue\u00f1o ideal\u00bb. Por Mar Solana"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/www.canal-literatura.com\/BLOG\/fotos\/castillo-Solana.jpg\"  alt=\"\" hspace=\"20\" align=\"right\" \/><\/p>\n<p>Un buen d\u00eda, Soberbia e Ingratitud, cansadas de dar vueltas siempre por el mismo sitio, llegaron a un curioso lugar en donde el sol refulg\u00eda con fuerza y no asfixiaba. El cielo, de un azul interminable, se precipitaba sobre las casas como una b\u00f3veda protectora. All\u00ed, lo diferente no llamaba la atenci\u00f3n, se integraba con naturalidad en el irregular conjunto de los ciudadanos que lo habitaban. Algunos ten\u00edan alas, otros grandes hocicos en lugar de nariz y la mayor\u00eda exhib\u00eda un cuerpo tan peculiar como el de los monstruos que pueblan nuestros sue\u00f1os.<br \/>\nSoberbia e lngratitud no tardaron en percibir una tranquilidad imperante que no se parec\u00eda en absoluto a la que antecede a una tormenta, aquella invitaba a quedarse, a saborear cada bocado de aire sintiendo la tibieza del sol en la piel.  Soberbia continuaba enfadada, a la defensiva ante cualquier gesto que no fuera la ira o la arrogancia. Su compa\u00f1era, Ingratitud, era incapaz de percibir todo lo bueno y hermoso de aquel sitio reci\u00e9n descubierto en su peregrino recorrido. Un caballero de mediana edad se acerc\u00f3 hacia ellas. Su porte robusto zarandeaba al caminar un bast\u00f3n de baquelita y una capa negra ondeaba al son de sus pasos, l\u00e1nguidos y sibilinos. Se detuvo ante ellas, su mirada se proyectaba a trav\u00e9s de unos ojos oscuros como el azabache:<br \/>\n?Hola, me llamo Miedo ?les espet\u00f3 sin m\u00e1s pre\u00e1mbulos.<br \/>\nComo es natural, Soberbia se sinti\u00f3 enojada, mientras Ingratitud le observaba con desd\u00e9n. Ambas comenzaron a inquietarse.<br \/>\n?Me marcho de este pa\u00eds, no he podido convencer a nadie. No son vulnerables a la dependencia, al apego o a la esclavitud. Aqu\u00ed se gobiernan a s\u00ed mismos y no necesitan leyes para convivir en paz. Cada uno sabe lo que est\u00e1 bien y lo que debe hacer en cada situaci\u00f3n. Y como son todos a cual m\u00e1s distinto, nadie necesita de mis servicios; lo extra\u00f1o y diferente no s\u00f3lo es aceptado, es aplaudido con amor. No se hacen da\u00f1o entre ellos y cualquiera, por el hecho de estar delante de otro, es acogido con entrega y respeto. Por eso todos mueren de viejos, de forma natural\u2026La familia Crimen, Enfermedad y Dolor acab\u00f3 en la m\u00e1s absoluta de las soledades, rechazados y apartados se dispersaron, pues nunca encontraron su hueco. Todo el mundo tiene un sitio para guarecerse y nadie est\u00e1 solo si no quiere estarlo.<br \/>\n?Pero\u2026 \u00a1habr\u00e1 guerras, por supuesto! ?exclam\u00f3 altanera Soberbia.<br \/>\n?Y hambre\u2026 pues cuanto mejor alimento da la tierra, m\u00e1s maltratada y menos respetada es si yo estoy cerca  ?core\u00f3 Ingratitud satisfecha.<br \/>\n?Hambre muri\u00f3 siendo apenas un beb\u00e9; al tam tam de una solemne ceremonia le dieron sepultura bajo los mantones de la fertilidad, que la sigue vigilando con celo para que no se le ocurra resucitar ?les explic\u00f3 Miedo, contundente?. Y as\u00ed, sobre la tumba de Hambre, cada uno aprende a cultivar sus propios alimentos. La tierra es profundamente venerada con m\u00e1gicos y ancestrales ritos y las cosechas son siempre abundantes para todos. Y en cuanto Guerra\u2026 Atra\u00eddo por su llamada llegu\u00e9 hasta aqu\u00ed, esperando encontrar a mis queridos hermanos, Angustia, Odio y Muerte, \u00a1mis compa\u00f1eros de batallas!\u2026Los tres perecieron estrangulados bajo las garras de cientos de besos y miles de c\u00e1lidos abrazos. Ya no existen grupos o enfrentamientos, pues la divisi\u00f3n atraer\u00eda de nuevo a todos los amigos y familiares de Desolaci\u00f3n que volver\u00edan a ajar la tierra y a asesinar a Fertilidad. S\u00f3lo existe la Gran Hermandad.<br \/>\n?Siempre habr\u00e1 algunos que sufran\u2026?a\u00f1adi\u00f3 Soberbia haciendo gala de una dignidad casi teatral.<br \/>\n?Nadie es feliz si existe una sola persona sufriendo, su alta sensibilidad lo percibe y acuden a socorrerle. La ayuda fluye como una caudalosa y l\u00edmpida corriente de r\u00edo. La soledad s\u00f3lo existe si es deseada y siempre hay unos que ense\u00f1an a otros a manejar el tim\u00f3n de la vida; el aprendizaje y las lecciones se van encadenando\u2026 Aqu\u00ed s\u00f3lo lloran en las despedidas, cuando alguien cruza el umbral de la muerte.<br \/>\n?Seguro que no  todos dan lo que pueden o no agradecen lo que deber\u00edan ?apostill\u00f3 Ingratitud con desafecci\u00f3n y frialdad.<br \/>\n?Todos comparten su vida por igual y dan a quien y lo que consideran oportuno en cada momento, sin esperar nada a cambio. Dan porque nace de sus corazones. Ego\u00edsmo y Manipulaci\u00f3n no se sintieron c\u00f3modos aqu\u00ed y huyeron muy pronto, se marcharon heridos y demacrados por los espont\u00e1neos y generosos gestos de Amor.<br \/>\n? \u00bfY c\u00f3mo se llama este lugar? ?interrog\u00f3 Soberbia a Miedo.<br \/>\n? Es el pa\u00eds de Ensue\u00f1o Ideal En este pa\u00eds, las profesiones m\u00e1s importantes son las de campesino y cuentacuentos. Siempre trabajan en grupos y no existen los entretenimientos en solitario como la televisi\u00f3n o los ordenadores. Han vuelto a la ancestral costumbre de reunirse para conversar, contar y escuchar cuentos, f\u00e1bulas y leyendas. En invierno, alrededor de una generosa hoguera, mientras asan casta\u00f1as y boniatos. En verano, auspiciados por la sombra de los \u00e1rboles, mientras comen fruta fresca, bayas y pi\u00f1ones\u2026Por cierto, \u00bfqui\u00e9nes sois vosotras?, \u00bfqu\u00e9 busc\u00e1is aqu\u00ed??quiso saber Miedo.<br \/>\n?Ella es Soberbia y yo soy Ingratitud. Est\u00e1bamos cansadas de la rigidez de nuestras vidas y decidimos emprender camino para buscar a nuestros padres. Soberbia, a su madre Tolerancia;  y yo, a mi padre Perd\u00f3n.<br \/>\n?El sabio matrimonio formado por Perd\u00f3n y Tolerancia viven satisfechos y en paz en aquel apartado castillo de la colina del Draco. Ellos ya no los necesitan, pero les agrada saber que a\u00fan siguen cerca\u2026nunca se sabe ?concluy\u00f3 Miedo en tono misterioso intentando hacer gala de su condici\u00f3n. Con una oscura y sinuosa sonrisa se volvi\u00f3 hacia las nuevas visitantes, iba a preguntarles si quer\u00edan hacer parte del camino con \u00e9l\u2026Pero Soberbia e Ingratitud ya se hab\u00edan alejado de su lado y comenzado a escalar la empinada y tortuosa colina que llevaba al castillo de Perd\u00f3n y Tolerancia. <\/p>\n<p>Villalba, 23 de abril de 2010.<br \/>\n<img decoding=\"async\" src=\"https:\/\/www.canal-literatura.com\/BLOG\/fotos\/mono9.jpg\" alt=\"\" align=\"right\" \/><br \/>\n<em><strong>Mar Solana<\/strong><\/em><br \/>\n<a href=\"http:\/\/www.marsolana.blogspot.com\/\" target=\"_blank\">Blog de la autora<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un buen d\u00eda, Soberbia e Ingratitud, cansadas de dar vueltas siempre por el mismo sitio, llegaron a un curioso lugar en donde el sol refulg\u00eda con fuerza y no asfixiaba. El cielo, de un azul interminable, se precipitaba sobre las casas como una b\u00f3veda protectora. All\u00ed, lo diferente no llamaba la atenci\u00f3n, se integraba con naturalidad en el irregular conjunto de los ciudadanos que lo habitaban. Algunos ten\u00edan alas, otros grandes hocicos en lugar de nariz y la mayor\u00eda exhib\u00eda un cuerpo tan peculiar como el de los monstruos que pueblan nuestros sue\u00f1os. Soberbia e lngratitud no tardaron en percibir&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/www.canal-literatura.com\/BLOG\/en-el-pais-del-ensueno-ideal-por-mar-solana\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-4066","post","type-post","status-publish","format-standard","hentry","category-cuentos"],"_links":{"self":[{"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/posts\/4066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/comments?post=4066"}],"version-history":[{"count":0,"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/posts\/4066\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/media?parent=4066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/categories?post=4066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/tags?post=4066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}