<br />
<b>Warning</b>:  Constant WP_DEFAULT_THEME already defined in <b>/home/u580195476/domains/canal-literatura.com/public_html/BLOG/wp/wp-config.php</b> on line <b>24</b><br />
<br />
<b>Warning</b>:  Constant ABSPATH already defined in <b>/home/u580195476/domains/canal-literatura.com/public_html/BLOG/wp/wp-config.php</b> on line <b>32</b><br />
{"id":2855,"date":"2010-01-23T11:10:02","date_gmt":"2010-01-23T10:10:02","guid":{"rendered":"https:\/\/www.canal-literatura.com\/BLOG\/?p=2855"},"modified":"2010-01-22T11:14:49","modified_gmt":"2010-01-22T10:14:49","slug":"el-jardin-de-los-suplicios-de-octave-mirbeau","status":"publish","type":"post","link":"https:\/\/www.canal-literatura.com\/BLOG\/el-jardin-de-los-suplicios-de-octave-mirbeau\/","title":{"rendered":"El jard\u00edn de los suplicios.  De Octave Mirbeau"},"content":{"rendered":"<p><strong>                       El libro.-<\/strong><br \/>\n<img decoding=\"async\" src=\"https:\/\/www.canal-literatura.com\/BLOG\/fotos\/CUBIERTA-JARDIN-SUPLICIOS.jpg\" alt=\"\" hspace=\"20\" align=\"left\" \/><\/p>\n<p>En El jard\u00edn de los suplicios, que sale a la venta este pr\u00f3ximo lunes 25 de enero, Mirbeau aborda la historia de un joven que, tras verse involucrado en diversas corrupciones pol\u00edticas, debe abandonar Francia con la excusa de una misi\u00f3n cient\u00edfica en la que participa como falso naturalista. Durante su viaje hacia Oriente conoce a Clara, una dama inglesa que le abrir\u00e1 los ojos a la realidad profunda de los instintos humanos y la falsedad e hipocres\u00eda de la civilizaci\u00f3n europea. Comenzar\u00e1 entonces un viaje a las ra\u00edces del placer y de la libertad, sin l\u00edmites ni condiciones, que le llevar\u00e1 al Jard\u00edn de los Suplicios: un lugar de China en el que la muerte y el placer se confunden hasta revelarse como una misma cosa.<\/p>\n<p>Calificada de \u00abmonstruo literario\u00bb por Pierre Michel, El jard\u00edn de los suplicios es una met\u00e1fora de las zonas m\u00e1s oscuras de la condici\u00f3n humana: la flor m\u00e1s hermosa parece que s\u00f3lo puede crecer gracias a la podredumbre \u2014\u2013moral y social\u2014 que la alimenta. Los traductores, C\u00e1mara y Front\u00e1n, advierten que \u00aben muchas de sus p\u00e1ginas es casi imposible respirar\u00bb, comparando algunos pasajes con \u00ablos m\u00e1s atroces de Sade\u00bb. Un fragmento de la novela puede descargarse desde la p\u00e1gina web de la editorial.<\/p>\n<p><strong>Autor<\/strong><\/p>\n<p><strong>Octave Mirbeau <\/strong>(1848 \u2013 1917) consagr\u00f3 su vida a la literatura: negro literario en sus comienzos, con el \u00e9xito altern\u00f3 narrativa, teatro y cr\u00edtica de ensayo y literatura. Despu\u00e9s de una adolescencia y juventud dif\u00edciles \u2014fue expulsado del colegio jesuita donde estudiaba\u2014, sufri\u00f3 una profunda crisis personal tras la que escribi\u00f3 alguna de las obras m\u00e1s influyentes de la literatura francesa moderna: El jard\u00edn de los suplicios (1899), El diario de una camarera (1900) y Los veinti\u00fan d\u00edas de un neurast\u00e9nico (1901). Hombre con inquietudes religiosas y valores anarquistas, creador complejo y comprometido con los debates morales y pol\u00edticos de su tiempo, gran estilista, su obra \u2014traducida a m\u00e1s de treinta idiomas\u2014 ha merecido los elogios de autores como Zola, Apollinaire, Brecht o Ionesco, y ejerce una influencia perdurable sobre la mejor literatura contempor\u00e1nea.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.canal-literatura.com\/BLOG\/fotos\/mono6.jpg\" alt=\"\" align=\"right\" \/><\/p>\n<p><a href=\"http:\/\/www.elolivoazul.es\/\" target=\"new\">Editorial Olivo Azul<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El libro.- En El jard\u00edn de los suplicios, que sale a la venta este pr\u00f3ximo lunes 25 de enero, Mirbeau aborda la historia de un joven que, tras verse involucrado en diversas corrupciones pol\u00edticas, debe abandonar Francia con la excusa de una misi\u00f3n cient\u00edfica en la que participa como falso naturalista. Durante su viaje hacia Oriente conoce a Clara, una dama inglesa que le abrir\u00e1 los ojos a la realidad profunda de los instintos humanos y la falsedad e hipocres\u00eda de la civilizaci\u00f3n europea. Comenzar\u00e1 entonces un viaje a las ra\u00edces del placer y de la libertad, sin l\u00edmites ni&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/www.canal-literatura.com\/BLOG\/el-jardin-de-los-suplicios-de-octave-mirbeau\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-2855","post","type-post","status-publish","format-standard","hentry","category-novedades-editoriales"],"_links":{"self":[{"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/posts\/2855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/comments?post=2855"}],"version-history":[{"count":0,"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/posts\/2855\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/media?parent=2855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/categories?post=2855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/tags?post=2855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}