<br />
<b>Warning</b>:  Constant WP_DEFAULT_THEME already defined in <b>/home/u580195476/domains/canal-literatura.com/public_html/BLOG/wp/wp-config.php</b> on line <b>24</b><br />
<br />
<b>Warning</b>:  Constant ABSPATH already defined in <b>/home/u580195476/domains/canal-literatura.com/public_html/BLOG/wp/wp-config.php</b> on line <b>32</b><br />
{"id":1221,"date":"2009-05-26T00:00:51","date_gmt":"2009-05-25T22:00:51","guid":{"rendered":"https:\/\/www.canal-literatura.com\/BLOG\/?p=1221"},"modified":"2009-05-26T00:05:49","modified_gmt":"2009-05-25T22:05:49","slug":"desde-alemania-para-carmen-posadas-por-susana-garcia-de-arriba","status":"publish","type":"post","link":"https:\/\/www.canal-literatura.com\/BLOG\/desde-alemania-para-carmen-posadas-por-susana-garcia-de-arriba\/","title":{"rendered":"Desde Alemania para Carmen Posadas. Por  Susana Garc\u00eda de Arriba"},"content":{"rendered":"<p><img decoding=\"async\" hspace=\"20\" src=\"http:\/\/www.canal-literatura.com\/Libros\/Caviar-Sardinas.jpg\" align=\"right\" border=\"0\"  \/><\/p>\n<p>He tenido la suerte de que el nombre \u00abCarmen Posadas\u00bb para mi est\u00e1 s\u00f3lo relacionado con una escritora de libros que esta muy amenudo formando parte de los cert\u00e1menes literarios del canal Literatura. Lo siento pero no conocia ni sus matrimonios ni su relacion con la \u00abalta\u00bb sociedad, ni me interesa. De echo ni tengo idea de su amistad con Isabel Presley ni tampoco me interesa. Me dedico a la ciencia y realmente lo m\u00e1ximo que recibo de la sociedad espa\u00f1ola es lo que muestran los telediarios. Por ello he podido leer \u00abHoy caviar y ma\u00f1ana sardinas\u00bb sin predisposici\u00f3n ni prejuicios. El libro me ha fascinado porque he vivido en varios paises y yo mejor que nadie s\u00e9 lo que ello conlleva. Ademas es que desde fuera parece que lo que se consigue ha sido gratis, porque una cae bien. Es dif\u00edcil incluso comunicar lo que ha supuesto sobrevivir y ademas tener \u00e9xito en otro pa\u00eds. El dinero no lo compra todo y las influencias de tener padres conocidos pueden ayudar o no. Las vivencias de la madre de Carmen Posadas son un an\u00e1lisis inteligente que cada directivo har\u00eda para luego establecer estrategias que le ayuden a alcanzar los objetivos que se haya propuesto. No todas las persona tienen esa capacidad de an\u00e1lisis. El punto de vista de una esposa y madre, con sus oblicaciones y responsabilidades, y su parte cr\u00edtica, que no tonta, de entender lo que ocurre a su alrededor. Lo que ocurre en esta familia lo podr\u00edamos extrapolar a cualquier otra familia de clase media. Porque la esencia no est\u00e1 en las realezas sino en las vivencias.<br \/>\nMe ha gustado mucho. Especialmente lo ameno que est\u00e1 redactado y con tanto detalle. Aquel que no entienda el libro o crea que es de \u00abtias marias\u00bb es porque no le ha dedicado suficiente tiempo a su madre o abuela. Esas son la vivencias de mujeres que &#8230; creo ya no existen. En muchas partes me acordaba de mi madre, mucho&#8230; en otras de mi amiga Xi.. . He conseguido amenizar a mi familia y a mi madre con las aventuras de la familia Posadas. Riendonos de vivencias similares y de la capacidad de supervivencia de algunas madres.<br \/>\nCarmen, enhorabuena, he dejado de leer las 4 \u00faltimas p\u00e1ginas porque no quiero cerrar el libro. Me animar\u00e9 a leer otro de tus libros, en cuanto vuelva a Espa\u00f1a busco el siguiente. <\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.canal-literatura.com\/BLOG\/fotos\/mono3.jpg\" align=\"right\" \/><br \/><br\n<em><strong> Susana Garc\u00eda de Arriba<\/strong><\/em><br \/>\nBraunschweig &#8211; 17\/05\/2009<\/p>\n","protected":false},"excerpt":{"rendered":"<p>He tenido la suerte de que el nombre \u00abCarmen Posadas\u00bb para mi est\u00e1 s\u00f3lo relacionado con una escritora de libros que esta muy amenudo formando parte de los cert\u00e1menes literarios del canal Literatura. Lo siento pero no conocia ni sus matrimonios ni su relacion con la \u00abalta\u00bb sociedad, ni me interesa. De echo ni tengo idea de su amistad con Isabel Presley ni tampoco me interesa. Me dedico a la ciencia y realmente lo m\u00e1ximo que recibo de la sociedad espa\u00f1ola es lo que muestran los telediarios. Por ello he podido leer \u00abHoy caviar y ma\u00f1ana sardinas\u00bb sin predisposici\u00f3n ni&#8230; <a class=\"continue-reading-link\" href=\"https:\/\/www.canal-literatura.com\/BLOG\/desde-alemania-para-carmen-posadas-por-susana-garcia-de-arriba\/\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-1221","post","type-post","status-publish","format-standard","hentry","category-opiniones"],"_links":{"self":[{"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/posts\/1221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/comments?post=1221"}],"version-history":[{"count":0,"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/posts\/1221\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/media?parent=1221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/categories?post=1221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.canal-literatura.com\/BLOG\/wp-json\/wp\/v2\/tags?post=1221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}