{"id":706,"date":"2011-07-04T14:59:06","date_gmt":"2011-07-04T12:59:06","guid":{"rendered":"http:\/\/www.canal-literatura.com\/8certamen\/?p=706"},"modified":"2011-07-04T14:59:06","modified_gmt":"2011-07-04T12:59:06","slug":"92-el-verano-del-cincuenta-y-ocho-por-becalus","status":"publish","type":"post","link":"https:\/\/www.canal-literatura.com\/8certamen\/92-el-verano-del-cincuenta-y-ocho-por-becalus\/","title":{"rendered":"92- El verano del cincuenta y ocho. Por Becalus"},"content":{"rendered":"<p>\u2013Mira pap\u00e1 ya viene. \u00a1Es ese!, \u00a1es ese! \u00a1Ya viene!, \u00a1ya viene!<\/p>\n<p>\u2013\u00a1Venga!, \u00a1todos preparados!. Coged cada uno sus cosas, que no se quede nada.<\/p>\n<p>Un largo silbido nos avisa de la entrada en la estaci\u00f3n del tren expreso en el que nos dispon\u00edamos a subir y que nos llevar\u00eda, despu\u00e9s de ocho horas de viaje, hasta nuestra casa en la playa de Pinedo.<!--more-->\u00a0Por fin aparece aquel ingenio mec\u00e1nico, la \u201clocomotora\u201d, resoplando entre una nube de vapor. A mi me parec\u00eda una especie de monstruo mitol\u00f3gico que, entre bufidos y silbidos, arrastraba una largu\u00edsima cola donde nos permit\u00eda subir a los humanos.<\/p>\n<p>De esa forma empez\u00e1bamos todos los a\u00f1os las vacaciones: pap\u00e1, mam\u00e1, la abuela Elo\u00edsa, mi hermanita Ana y \u201cPeluso\u201d: un caniche enano, de color gris, juguet\u00f3n y revoltoso. A \u201cPeluso\u201d lo llev\u00e1bamos dentro de una cesta de viaje, era la \u00fanica forma en que pod\u00eda venir con nosotros, aunque nunca tuve demasiado claro si estaba permitido por la compa\u00f1\u00eda de ferrocarriles que los perros viajaran con las personas, pero lo cierto es que el nuestro lo hac\u00eda; aunque recuerdo que, cuando aparec\u00eda el revisor, mis padres siempre ingeniaban algo: aparentemente inocente; que apartaba a \u201cPeluso\u201d de su presencia. Hasta una vez la abuela Elo\u00edsa se encerr\u00f3 con \u00e9l en el cuarto de aseo, hasta que pas\u00f3 el interventor.<\/p>\n<p>Era el mes de Agosto de 1.958 y aquellos viajes en tren eran para mi, un chico de diez a\u00f1os, una de las mayores aventuras que era posible vivir sin hacer nada prohibido, como pod\u00eda ser: ir a comer fruta en los campos: siempre atentos a escapar de los guardas y sus tiros de sal, o subir a escondidas a cualquier terraza de las que rodeaban al cine de verano: para ver sin pagar las pel\u00edculas \u201cno toleradas\u201d; con el riesgo a\u00f1adido de regresar colgado por la oreja de la mano de alg\u00fan guardia municipal hasta el domicilio paterno, donde aguardaba una buena rega\u00f1ina, o jugar a \u201cm\u00e9dicos\u201d: eso si que era excitante y arriesgado y algunos mas que prefiero callar por no escandalizar a nadie.<\/p>\n<p>Obvio decir que viaj\u00e1bamos en tercera clase, la mas econ\u00f3mica, eran compartimentos de ocho viajeros que siempre iban a rebosar y, en ellos escuch\u00e9 historias reales, o fantas\u00edas que lo parec\u00edan, que a veces era casi imposible distinguir lo uno de lo otro. Recuerdo: los asientos de hule, las ventanillas de \u201cguillotina\u201d, la carbonilla que sol\u00eda entrar en los ojos si te atrev\u00edas a ir asomado por una de ellas, el revisor que pasaba perforando los billetes y, sobre todo, la hora de la comida: cuando los ocupantes del compartimento sacaban sus provisiones y las compart\u00edan entre todos. Luego los mayores jugaban a las cartas, siempre hab\u00eda alguna baraja a mano, y mi hermana Anita y yo nos perd\u00edamos curioseando por los distintos vagones hasta que, indefectiblemente, acab\u00e1bamos en uno de primera clase de donde tambi\u00e9n, inevitablemente, nos arrojaba el revisor con cajas destempladas y amenazas de cobrar el suplemento a mis padres. Anita tiene dos a\u00f1os menos que yo.<\/p>\n<p>Aquel a\u00f1o compartimos departamento con un matrimonio de Gallocanta, un pueblecito de la provincia de Zaragoza que iban a ver el mar por primera vez. El nombre del pueblo me hizo gracia y, en mi inocencia infantil, llegue a pensar que \u201cdeb\u00edan tener un gallo que cantaba para indicar la hora en punto, o algo as\u00ed\u201d. El marido era casi calvo, muy bajito y algo rechoncho; casi no hablaba, solo asent\u00eda con resignados movimientos de cabeza las indiscutibles afirmaciones de su mujer: gorda como un hipop\u00f3tamo, le sacaba casi la cabeza y ten\u00eda unos pellillos negros encima del labio superior que le daban un aspecto bastante sobrecogedor. Los dos andar\u00edan por los cincuenta a\u00f1os y creo que el marido le ten\u00eda algo de miedo a su mujer. A\u00fan recuerdo algo que dijo el pobre hombre que caus\u00f3 grandes risas entre todos los que viajaban en ese compartimento y furiosas miradas de su mujer que, al instante, se lanz\u00f3 a defenderlo.<\/p>\n<p>\u2013Nosotros no hemos visto nunca el mar y para eso vamos hasta un pueblecito que se llama Cullera. \u2013 Dijo el hombre con una media sonrisa, mientras secaba un chorret\u00f3n de sudor que le resbalaba de su calva.<\/p>\n<p>\u2013Les gustar\u00e1 Cullera y, ver\u00e1n que grande es el mar. Nunca habr\u00e1n visto tanta agua junta. \u2013Respondi\u00f3 mi madre de forma inocente, sin saber lo que su contestaci\u00f3n iba a desencadenar.<\/p>\n<p>\u2013Pues ser\u00e1 muy grande pero dicen eso por que no han visto la laguna de nuestro pueblo. \u201cHabr\u00eda que verlos juntos\u201d. \u2013Contest\u00f3 ufano Andr\u00e9s Cejudo, ese era el nombre del marido. Tampoco entend\u00eda yo: como pod\u00eda llamarse Cejudo, si casi no ten\u00eda cejas.\u00a0<\/p>\n<p>Lo dijo tan convencido que cuando le escucharon: mis padres, el militar y el representante; que eran junto con Anita y conmigo los que viaj\u00e1bamos en compartimento 12C se quedaron en silencio, sin saber demasiado bien que hacer, si tomarlo en serio o re\u00edrse de tama\u00f1a tonter\u00eda. Pero yo era un ni\u00f1o de diez a\u00f1os como ya he dicho, y me puse a re\u00edr como un loco, Anita que me imitaba en todo tambi\u00e9n se puso a re\u00edr se\u00f1alando al pobre Cejudo. Luego fue el soldado, que hac\u00eda \u201cla mili\u201d en Valladolid y viajaba de permiso hasta Gand\u00eda, el que se desternillaba de una forma tan contagiosa que mis padres y el representante tambi\u00e9n comenzaron a tronchase. Entonces fue cuando Felisa poni\u00e9ndose en p\u00ede muy ofendida por las burlas hacia su esposo, comenz\u00f3 a rugir de una forma tan agresiva que todos nos quedamos sobrecogidos y en silencio.<\/p>\n<p>\u2013\u00a1Vay\u00e1monos de este compartimento Andr\u00e9s! Que estos ignorantes no han visto nuestra laguna y no saben lo grande que es. \u00a1El mar!, \u00a1el mar! \u00a1tampoco ser\u00e1 para tanto! \u2013Y dando un tir\u00f3n de sus maletas que, en aquellos trenes, iban en una especie de estanter\u00eda sobre las cabezas de los pasajeros. Salieron muy dignos a buscar otro sitio donde terminar su viaje.<\/p>\n<p>Durante el resto del trayecto, tanto el soldado como el representante de art\u00edculos de ferreter\u00eda no pararon de hacer chistes en los que siempre hab\u00eda algo que, por supuesto, no era tan grande como la laguna de Gallocanta.<\/p>\n<p>A mi, el representante no me cay\u00f3 bien. Era un tipo de aspecto engre\u00eddo y con unos aires de autosuficiencia, como si supiese mas que nadie. En todas las controversias la \u00faltima palabra ten\u00eda que ser suya. Creo que a mis padres tampoco les gust\u00f3. La abuela estuvo casi todo el viaje dormida, menos cuando se fue a esconder a \u201cPeluso\u201d en el retrete de la vista del revisor.<\/p>\n<p>Desde la Estaci\u00f3n de Ferrocarril hasta nuestra casa de Pinedo, un pueblecito costero muy pr\u00f3ximo a Valencia, \u00edbamos en un tranv\u00eda y, si los chicos de ahora hubieseis podido ver, el \u201cnumerito\u201d que organiz\u00e1bamos para subir en aquellos armatostes con todo muestro equipaje y \u201cPeluso\u201d de estraperlo, mas de uno hubiese cogido dolor de tripa de tanto re\u00edrse. La llegada a la casa no desmerec\u00eda en nada a todo lo que,Anita y yo nos hab\u00edamos divertido en el trayecto: mis padres hablando a voces sobre como estaba la casa, la cantidad de polvo que se hab\u00eda acumulado, donde colocar las cosas \u2013eso nunca lo entend\u00ed, siempre \u00edbamos a la misma casa y todos los a\u00f1os discut\u00edan sobre como organizar las cosas\u2013 y por si eso no era suficiente; \u201cPeluso\u201d ladrando como si quisiera desquitarse de todo el silencio que hab\u00eda guardado durante el viaje.<\/p>\n<p>Por aquel entonces Ana y yo eramos inseparables, no es que luego nos llev\u00e1ramos mal, pero en aquellos a\u00f1os, ella me ve\u00eda como su \u201cHERMANO MAYOR\u201d as\u00ed, con may\u00fasculas, me obedec\u00eda en todo y creo que ten\u00eda un concepto demasiado elevado de mi inteligencia, valent\u00eda y todo lo que sonase a bueno.<\/p>\n<p>Nuestra casa estaba justo enfrente de la playa y la \u00fanica distracci\u00f3n a la que ten\u00edamos acceso: era jugar en la arena, ba\u00f1arnos en la orilla bajo la estricta vigilancia de nuestra madre y rebuscar entre las rocas para cazar cangrejos, con los que mam\u00e1 preparaba unos arroces espectaculares. Tambi\u00e9n estaba \u201cPeluso\u201d, en aquellos a\u00f1os pod\u00edas llevar tu perro a la playa y no pasaba nada, bueno si que pasaba y es que nos divert\u00edamos tirando piedras que \u00e9l buscaba entre ladridos de satisfacci\u00f3n.<\/p>\n<p>Al segundo d\u00eda de estar en Pinedo, mi madre que hablaba con todo el mundo, se hizo amiga de otra madre que, casualmente, ocupaban una casa no demasiado lejos de la nuestra. Se cayeron tan bien que, esa misma noche vinieron a cenar a nuestra casa: el matrimonio y sus dos hijos: Anto\u00f1\u00edn de la misma edad que Anita, y Mercedes un a\u00f1o mas joven que yo. Cuando la vi me qued\u00e9 con la boca abierta, y as\u00ed hubiese estado toda la noche si no fuera porque ten\u00eda que cerrarla para masticar. Al d\u00eda siguiente en la playa, las dos madres: la m\u00eda y la de Mercedes, como no pod\u00eda ser de otra forma se pusieron juntas a tomar el sol y, el tr\u00edo que form\u00e1bamos hasta entonces: Anita y yo, con \u201cPelus\u00edn\u201d \u2013que era como le llam\u00e1bamos cuando est\u00e1bamos de buen humor\u2013 se transform\u00f3 en un quinteto, al agregarse: Anto\u00f1\u00edn y Mercedes. Aquel fue un verano inolvidable, me despertaba deseando bajar hasta la arena solo por disfrutar de la compa\u00f1\u00eda de Mercedes. Nuestros juegos y distracciones siguieron siendo los mismos, pero ahora todo era mas divertido.<\/p>\n<p>Cuando cierro los ojos todav\u00eda puedo verla: con su ba\u00f1ador azul, sus coletas y el flotador con el que se ba\u00f1aba. Creo que, sin llegar a comprender lo que me ocurr\u00eda, aquel verano me enamor\u00e9.<\/p>\n<p>Casi todas las noches nuestras familias cenaban juntas, bien en su casa o en la nuestra, apenas nos permit\u00edan levantarnos de la mesa nos apart\u00e1bamos hasta la orilla de la playa, ya dije que nuestras casas estaban al borde de la arena, y con el pretexto de pasear a \u201cPeluso\u201d nos pod\u00edamos retirar un trecho para hablar de los temas mas banales, \u00e9ramos felices as\u00ed, estando el uno junto al otro.<\/p>\n<p>Como no existe la dicha eterna, nuestro veraneo lleg\u00f3 a su fin y tuvimos que regresar a Madr\u00edd. Para Anita y para mi, el viaje de regreso era como el ep\u00edlogo de una historia: la de ese veraneo. Volv\u00edan a repetirse escenas ya vividas: en el tranv\u00eda, en la estaci\u00f3n, en el tren&#8230;<\/p>\n<p>Seguimos viajando a Pinedo durante muchos a\u00f1os, siempre manten\u00eda la secreta esperanza de encontrar otra vez a Mercedes, pero no volvimos a coincidir las dos familias. Desde aquel a\u00f1o, mis veraneos siempre tuvieron un poso de tristeza, echaba en falta: su compa\u00f1\u00eda, su risa, sus coletas, el ba\u00f1ador azul, el flotador&#8230;<\/p>\n<p>Querr\u00e9is saber si volv\u00ed a a verla: Es la madre de mis hijos, pero de eso hablar\u00e9 otro d\u00eda&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2013Mira pap\u00e1 ya viene. \u00a1Es ese!, \u00a1es ese! \u00a1Ya viene!, \u00a1ya viene! \u2013\u00a1Venga!, \u00a1todos preparados!. Coged cada uno sus cosas, que no se quede nada. Un largo silbido nos avisa de la entrada en la estaci\u00f3n del tren expreso en el que nos dispon\u00edamos a subir y que nos llevar\u00eda, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-706","post","type-post","status-publish","format-standard","hentry","category-relatos"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.canal-literatura.com\/8certamen\/wp-json\/wp\/v2\/posts\/706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.canal-literatura.com\/8certamen\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.canal-literatura.com\/8certamen\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.canal-literatura.com\/8certamen\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.canal-literatura.com\/8certamen\/wp-json\/wp\/v2\/comments?post=706"}],"version-history":[{"count":4,"href":"https:\/\/www.canal-literatura.com\/8certamen\/wp-json\/wp\/v2\/posts\/706\/revisions"}],"predecessor-version":[{"id":710,"href":"https:\/\/www.canal-literatura.com\/8certamen\/wp-json\/wp\/v2\/posts\/706\/revisions\/710"}],"wp:attachment":[{"href":"https:\/\/www.canal-literatura.com\/8certamen\/wp-json\/wp\/v2\/media?parent=706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.canal-literatura.com\/8certamen\/wp-json\/wp\/v2\/categories?post=706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.canal-literatura.com\/8certamen\/wp-json\/wp\/v2\/tags?post=706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}